{"id":40253,"date":"2026-08-31T15:57:21","date_gmt":"2026-08-31T15:57:21","guid":{"rendered":"https:\/\/sitechecker.pro\/?page_id=40253"},"modified":"2026-08-31T15:57:21","modified_gmt":"2026-08-31T15:57:21","slug":"a-cognitiveseo-alternative-with-ai-visibility-and-flat-credit-free-pricing","status":"publish","type":"page","link":"https:\/\/sitechecker.pro\/tr\/cognitiveseo-alternative\/","title":{"rendered":"CognitiveSEO alternative"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"alternative-page-template.php","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/sitechecker.pro\/tr\/wp-json\/wp\/v2\/pages\/40253"}],"collection":[{"href":"https:\/\/sitechecker.pro\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sitechecker.pro\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sitechecker.pro\/tr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sitechecker.pro\/tr\/wp-json\/wp\/v2\/comments?post=40253"}],"version-history":[{"count":0,"href":"https:\/\/sitechecker.pro\/tr\/wp-json\/wp\/v2\/pages\/40253\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitechecker.pro\/tr\/wp-json\/wp\/v2\/media?parent=40253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitechecker.pro\/tr\/wp-json\/wp\/v2\/categories?post=40253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitechecker.pro\/tr\/wp-json\/wp\/v2\/tags?post=40253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}