{"id":39988,"date":"2026-07-22T12:34:49","date_gmt":"2026-07-22T12:34:49","guid":{"rendered":"https:\/\/sitechecker.pro\/?page_id=39988"},"modified":"2026-07-22T14:19:08","modified_gmt":"2026-07-22T14:19:08","slug":"chatgpt-visibility-tracker","status":"publish","type":"page","link":"https:\/\/sitechecker.pro\/it\/chatgpt-visibility-tracker\/","title":{"rendered":"ChatGPT visibility tracker"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10409641,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"new-design-template.php","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/sitechecker.pro\/it\/wp-json\/wp\/v2\/pages\/39988"}],"collection":[{"href":"https:\/\/sitechecker.pro\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sitechecker.pro\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sitechecker.pro\/it\/wp-json\/wp\/v2\/users\/10409641"}],"replies":[{"embeddable":true,"href":"https:\/\/sitechecker.pro\/it\/wp-json\/wp\/v2\/comments?post=39988"}],"version-history":[{"count":0,"href":"https:\/\/sitechecker.pro\/it\/wp-json\/wp\/v2\/pages\/39988\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitechecker.pro\/it\/wp-json\/wp\/v2\/media?parent=39988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitechecker.pro\/it\/wp-json\/wp\/v2\/categories?post=39988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitechecker.pro\/it\/wp-json\/wp\/v2\/tags?post=39988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}